{"id":56,"date":"2017-10-21T19:23:41","date_gmt":"2017-10-21T19:23:41","guid":{"rendered":"http:\/\/www.raijmr.com\/riap\/?page_id=56"},"modified":"2023-01-01T05:33:24","modified_gmt":"2023-01-01T05:33:24","slug":"submit-book","status":"publish","type":"page","link":"https:\/\/raijmr.com\/riap\/submit-book\/","title":{"rendered":"Submit Book"},"content":{"rendered":"<div class=\"cf7sg-container\"><div id=\"cf7sg-form-submit-book\" class=\"cf7-smart-grid has-date has-grid key_submit-book\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f6308-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"6308\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/riap\/wp-json\/wp\/v2\/pages\/56#wpcf7-f6308-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"6308\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6308-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_key\" value=\"submit-book\" \/><input type=\"hidden\" name=\"_cf7sg_toggles\" value=\"\" \/><input type=\"hidden\" name=\"_cf7sg_version\" value=\"4.15.8\" \/><input type=\"hidden\" name=\"_wpnonce\" value=\"5603906a4b\" \/>\n<\/fieldset>\n<div class=\"container\">\n  <div class=\"row\">\n    <div class=\"columns full\">\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns full\">\n            <div class=\"field\"><label>Name of Publication (Powered By Rudra Education Trust &amp; Riddhi Education Trust)<em>*<\/em><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"journal-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" readonly=\"readonly\" aria-required=\"true\" aria-invalid=\"false\" value=\"RET International Academic Publishing\" type=\"text\" name=\"journal-name\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns full\">\n            <div class=\"field\"><label>Acquisition Edited by<em>*<\/em><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Chief-Editor\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" readonly=\"readonly\" aria-required=\"true\" aria-invalid=\"false\" value=\"RET International Academic Publishing (A global platform for ISBN International publishing unit with editorial &amp; publishing services)\" type=\"text\" name=\"Chief-Editor\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns full\">\n            <div class=\"field\"><label>Attach Your Photo<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-photo\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\"audio\/*,video\/*,image\/*\" aria-invalid=\"false\" type=\"file\" name=\"your-photo\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns full\">\n            <div class=\"field\"><label>Your Name<em>*<\/em><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Education Qualification<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"qualification\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"qualification\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Date Of Birth<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"birthdate\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-date\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"birthdate\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Research Topic<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Research\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Research\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Subject<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Subject\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns full\">\n            <div class=\"field\"><label>Research Experience<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Research-Experience\"><textarea cols=\"40\" rows=\"5\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"Research-Experience\"><\/textarea><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Faculty<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Faculty\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Faculty\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>College \/ University Name<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"College-University\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"College-University\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns full\">\n            <div class=\"field\"><label>Home Address<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Home-Address\"><textarea cols=\"40\" rows=\"5\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"Home-Address\"><\/textarea><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Country<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Country\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Country\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>State<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"State\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"State\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>City<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"City\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"City\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>PIN Code<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"pincode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"pincode\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Landline<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Landline\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Landline\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Email<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-text wpcf7-validates-as-email\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"Email\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Mobile 01<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Mobile01\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Mobile01\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Mobile 02<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Mobile02\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Mobile02\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns full\">\n            <div class=\"field\"><label>Website (if any)<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Website\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Website\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Upload Manuscript<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Paper\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\"audio\/*,video\/*,image\/*\" aria-invalid=\"false\" type=\"file\" name=\"Paper\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Upload Plagiarism Report<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"plagiarism\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\"audio\/*,video\/*,image\/*\" aria-invalid=\"false\" type=\"file\" name=\"plagiarism\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Upload Original evidences of Manuscript<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"rough\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\"audio\/*,video\/*,image\/*\" aria-invalid=\"false\" type=\"file\" name=\"rough\" \/><\/span>\n              <p class=\"info-tip\">Upload the evidences before you prepared your book's manuscript like your original handwritten Papers\/Notes, Primary &amp; Secondary sources of used texts\/quotations\/data, footnotes, References &amp; all row materials etc.<\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Signature<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Signature\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\"audio\/*,video\/*,image\/*\" aria-invalid=\"false\" type=\"file\" name=\"Signature\" \/><\/span>\n              <p class=\"info-tip\">Author's Signatures<\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Name of Book Reviewer 01<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Reviewer01\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Reviewer who pre-reviewed your book before submitting here\" value=\"\" type=\"text\" name=\"Reviewer01\" \/><\/span>\n              <p class=\"info-tip\">Reviewer who pre-reviewed your book before submitting here<\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Name of Book Reviewer 02<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Reviewer02\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Reviewer who pre-reviewed your book before submitting here\" value=\"\" type=\"text\" name=\"Reviewer02\" \/><\/span>\n              <p class=\"info-tip\">Reviewer who pre-reviewed your book before submitting here<\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Qualification of Reviewer 01<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Qualification-Reviewer01\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Qualification-Reviewer01\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Qualification of Reviewer 02<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Qualification-Reviewer02\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Qualification-Reviewer02\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Experiences of Reviewer 01<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Experience-Reviewer01\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"Experience-Reviewer01\"><\/textarea><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Experiences of Reviewer 02<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Experience-Reviewer02\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"Experience-Reviewer02\"><\/textarea><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Designation of Reviewer 01<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Designation-Reviewer01\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Designation-Reviewer01\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Designation of Reviewer 02<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Designation-Reviewer02\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Designation-Reviewer02\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Mob No. of Reviewer 01<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Reviewer-Mobile01\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Reviewer-Mobile01\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Mob No. of Reviewer 02<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Reviewer-Mobile02\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Reviewer-Mobile02\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Email of Reviewer 01<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Reviewer-Email01\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-text wpcf7-validates-as-email\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"Reviewer-Email01\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Email of Reviewer 02<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Reviewer-Email02\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-text wpcf7-validates-as-email\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"Reviewer-Email02\" \/><\/span>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Signature of Reviewer 01<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Reviewer-Signature01\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\"audio\/*,video\/*,image\/*\" aria-invalid=\"false\" type=\"file\" name=\"Reviewer-Signature01\" \/><\/span>\n              <p class=\"info-tip\">Reviewer who pre-reviewed your book before submitting here<\/p>\n            <\/div>\n          <\/div>\n          <div class=\"columns one-half\">\n            <div class=\"field\"><label>Signature of Reviewer 02<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"Reviewer-Signature02\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\"audio\/*,video\/*,image\/*\" aria-invalid=\"false\" type=\"file\" name=\"Reviewer-Signature02\" \/><\/span>\n              <p class=\"info-tip\">Reviewer who pre-reviewed your book before submitting here<\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"columns full\">\n            <div class=\"field\"><label><\/label><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Continue\" \/>\n              <p class=\"info-tip\"><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Name of Publication (Powered By Rudra Education Trust &amp; Riddhi Education Trust)* Acquisition Edited by* Attach Your Photo Your Name* Education Qualification Date Of Birth Research Topic Subject Research Experience Faculty College \/ University Name Home Address Country State City PIN Code Landline Email Mobile 01 Mobile 02 Website (if any) Upload Manuscript Upload Plagiarism [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-56","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/raijmr.com\/riap\/wp-json\/wp\/v2\/pages\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raijmr.com\/riap\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/raijmr.com\/riap\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/raijmr.com\/riap\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/raijmr.com\/riap\/wp-json\/wp\/v2\/comments?post=56"}],"version-history":[{"count":1,"href":"https:\/\/raijmr.com\/riap\/wp-json\/wp\/v2\/pages\/56\/revisions"}],"predecessor-version":[{"id":6992,"href":"https:\/\/raijmr.com\/riap\/wp-json\/wp\/v2\/pages\/56\/revisions\/6992"}],"wp:attachment":[{"href":"https:\/\/raijmr.com\/riap\/wp-json\/wp\/v2\/media?parent=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}